{"id":1412,"count":0,"description":"","link":"https:\/\/cliniquematignon.ch\/it\/zone\/maniglie-dellamore\/","name":"Maniglie dell'amore","slug":"maniglie-dellamore","taxonomy":"area_treatment","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Maniglie dell&#039;amore - Medicina estetica - Matignon - Svizzera<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cliniquematignon.ch\/it\/zone\/maniglie-dellamore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Maniglie dell&#039;amore\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cliniquematignon.ch\/it\/zone\/maniglie-dellamore\/\" \/>\n<meta property=\"og:site_name\" content=\"Matignon\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cliniquematignon.ch\/wp-content\/uploads\/2023\/10\/opengraph-matignon-1200-x-675-px..png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/zone\\\/maniglie-dellamore\\\/\",\"url\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/zone\\\/maniglie-dellamore\\\/\",\"name\":\"Maniglie dell'amore - Medicina estetica - Matignon - Svizzera\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/zone\\\/maniglie-dellamore\\\/#breadcrumb\"},\"inLanguage\":\"it-CH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/zone\\\/maniglie-dellamore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Casa\",\"item\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/casa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maniglie dell'amore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/\",\"name\":\"Matignon\",\"description\":\"M\u00e9decine esth\u00e9tique\",\"publisher\":{\"@id\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/#organization\",\"name\":\"Matignon\",\"url\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-CH\",\"@id\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cliniquematignon.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/mat-logo-black..svg\",\"contentUrl\":\"https:\\\/\\\/cliniquematignon.ch\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/mat-logo-black..svg\",\"width\":1,\"height\":1,\"caption\":\"Matignon\"},\"image\":{\"@id\":\"https:\\\/\\\/cliniquematignon.ch\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lescliniquesmatignon\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Maniglie dell'amore - Medicina estetica - Matignon - Svizzera","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cliniquematignon.ch\/it\/zone\/maniglie-dellamore\/","og_locale":"it_IT","og_type":"article","og_title":"Archives des Maniglie dell'amore","og_url":"https:\/\/cliniquematignon.ch\/it\/zone\/maniglie-dellamore\/","og_site_name":"Matignon","og_image":[{"width":1200,"height":675,"url":"https:\/\/cliniquematignon.ch\/wp-content\/uploads\/2023\/10\/opengraph-matignon-1200-x-675-px..png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cliniquematignon.ch\/it\/zone\/maniglie-dellamore\/","url":"https:\/\/cliniquematignon.ch\/it\/zone\/maniglie-dellamore\/","name":"Maniglie dell'amore - Medicina estetica - Matignon - Svizzera","isPartOf":{"@id":"https:\/\/cliniquematignon.ch\/it\/#website"},"breadcrumb":{"@id":"https:\/\/cliniquematignon.ch\/it\/zone\/maniglie-dellamore\/#breadcrumb"},"inLanguage":"it-CH"},{"@type":"BreadcrumbList","@id":"https:\/\/cliniquematignon.ch\/it\/zone\/maniglie-dellamore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Casa","item":"https:\/\/cliniquematignon.ch\/it\/casa\/"},{"@type":"ListItem","position":2,"name":"Maniglie dell'amore"}]},{"@type":"WebSite","@id":"https:\/\/cliniquematignon.ch\/it\/#website","url":"https:\/\/cliniquematignon.ch\/it\/","name":"Matignon","description":"M\u00e9decine esth\u00e9tique","publisher":{"@id":"https:\/\/cliniquematignon.ch\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cliniquematignon.ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-CH"},{"@type":"Organization","@id":"https:\/\/cliniquematignon.ch\/it\/#organization","name":"Matignon","url":"https:\/\/cliniquematignon.ch\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-CH","@id":"https:\/\/cliniquematignon.ch\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cliniquematignon.ch\/wp-content\/uploads\/2023\/06\/mat-logo-black..svg","contentUrl":"https:\/\/cliniquematignon.ch\/wp-content\/uploads\/2023\/06\/mat-logo-black..svg","width":1,"height":1,"caption":"Matignon"},"image":{"@id":"https:\/\/cliniquematignon.ch\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lescliniquesmatignon\/"]}]}},"_links":{"self":[{"href":"https:\/\/cliniquematignon.ch\/it\/wp-json\/wp\/v2\/area_treatment\/1412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cliniquematignon.ch\/it\/wp-json\/wp\/v2\/area_treatment"}],"about":[{"href":"https:\/\/cliniquematignon.ch\/it\/wp-json\/wp\/v2\/taxonomies\/area_treatment"}],"wp:post_type":[{"href":"https:\/\/cliniquematignon.ch\/it\/wp-json\/wp\/v2\/treatment?area_treatment=1412"},{"href":"https:\/\/cliniquematignon.ch\/it\/wp-json\/wp\/v2\/product?area_treatment=1412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}